{"id":135,"date":"2022-12-26T08:47:22","date_gmt":"2022-12-26T08:47:22","guid":{"rendered":"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/?page_id=135"},"modified":"2026-06-09T15:28:26","modified_gmt":"2026-06-09T07:28:26","slug":"elementor-lambang","status":"publish","type":"page","link":"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-lambang\/","title":{"rendered":"POLDA KALSEL #lambang"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"135\" class=\"elementor elementor-135\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f00ad90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f00ad90\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b464be6\" data-id=\"b464be6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-725e4dff elementor-widget elementor-widget-image\" data-id=\"725e4dff\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.9.2 - 21-12-2022 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kalsel.polri.go.id\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"120\" src=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/uploads\/2022\/12\/logo-kalselnew.gif\" class=\"attachment-large size-large wp-image-9\" alt=\"\" style=\"width:100%;height:24%;max-width:500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73942041 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73942041\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38c138f2\" data-id=\"38c138f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57e9fbde elementor-widget elementor-widget-image\" data-id=\"57e9fbde\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kalsel.polri.go.id\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1273\" height=\"384\" src=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/uploads\/2026\/06\/Header-Web-POLDA-KALSEL-2026-copy.jpg\" class=\"attachment-full size-full wp-image-893\" alt=\"\" srcset=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/uploads\/2026\/06\/Header-Web-POLDA-KALSEL-2026-copy.jpg 1273w, https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/uploads\/2026\/06\/Header-Web-POLDA-KALSEL-2026-copy-300x90.jpg 300w, https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/uploads\/2026\/06\/Header-Web-POLDA-KALSEL-2026-copy-1024x309.jpg 1024w, https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/uploads\/2026\/06\/Header-Web-POLDA-KALSEL-2026-copy-768x232.jpg 768w\" sizes=\"auto, (max-width: 1273px) 100vw, 1273px\" style=\"width:100%;height:30.16%;max-width:1273px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c10b6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c10b6c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3da1f22\" data-id=\"3da1f22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-305145aa e-transform elementor-widget__width-inherit elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"305145aa\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-nav-menu.min.css\">\t\t\t<nav migration_allowed=\"1\" migrated=\"0\" role=\"navigation\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-background e--animation-grow\">\n\t\t\t\t<ul id=\"menu-1-305145aa\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-665\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-365\/\" class=\"elementor-item\">KONTAK<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-667\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-200\/\" class=\"elementor-item\">VISI MISI<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-666\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-215\/\" class=\"elementor-item\">STRUKTUR<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-669\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-lambang\/\" class=\"elementor-item\">LAMBANG<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-674\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-236\/\" class=\"elementor-item\">PEDOMAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-668\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-144\/\" class=\"elementor-item\">SEJARAH<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-673\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-223\/\" class=\"elementor-item\">KAPOLDA<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-670\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-279\/\" class=\"elementor-item\">SEMBOYAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-671\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-248\/\" class=\"elementor-item\">MARS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-672\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-258\/\" class=\"elementor-item\">BHAYANGKARI<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-700\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/polda-kaslel-hari-juang-polri\/\" class=\"elementor-item\">HARI JUANG POLRI<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" role=\"navigation\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-305145aa\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-665\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-365\/\" class=\"elementor-item\" tabindex=\"-1\">KONTAK<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-667\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-200\/\" class=\"elementor-item\" tabindex=\"-1\">VISI MISI<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-666\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-215\/\" class=\"elementor-item\" tabindex=\"-1\">STRUKTUR<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-669\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-lambang\/\" class=\"elementor-item\" tabindex=\"-1\">LAMBANG<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-674\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-236\/\" class=\"elementor-item\" tabindex=\"-1\">PEDOMAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-668\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-144\/\" class=\"elementor-item\" tabindex=\"-1\">SEJARAH<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-673\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-223\/\" class=\"elementor-item\" tabindex=\"-1\">KAPOLDA<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-670\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-279\/\" class=\"elementor-item\" tabindex=\"-1\">SEMBOYAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-671\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-248\/\" class=\"elementor-item\" tabindex=\"-1\">MARS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-672\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-258\/\" class=\"elementor-item\" tabindex=\"-1\">BHAYANGKARI<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-700\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/polda-kaslel-hari-juang-polri\/\" class=\"elementor-item\" tabindex=\"-1\">HARI JUANG POLRI<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66b3449 elementor-widget elementor-widget-heading\" data-id=\"66b3449\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.9.2 - 21-12-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">LAMBANG KESATUAN<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4123b31 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4123b31\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1686e1e\" data-id=\"1686e1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-caad351\" data-id=\"caad351\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-23eca39\" data-id=\"23eca39\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ae0d03 elementor-widget elementor-widget-image\" data-id=\"6ae0d03\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/uploads\/2022\/12\/Lambang-Polda-Kalsel-emboss-724x1024.png\" class=\"attachment-large size-large wp-image-398\" alt=\"\" srcset=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/uploads\/2022\/12\/Lambang-Polda-Kalsel-emboss-724x1024.png 724w, https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/uploads\/2022\/12\/Lambang-Polda-Kalsel-emboss-212x300.png 212w, https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/uploads\/2022\/12\/Lambang-Polda-Kalsel-emboss-768x1086.png 768w, https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-content\/uploads\/2022\/12\/Lambang-Polda-Kalsel-emboss.png 819w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" style=\"width:100%;height:141.39%;max-width:819px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-dabd493\" data-id=\"dabd493\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-c625ac6\" data-id=\"c625ac6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20811aab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20811aab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-684c1cdb\" data-id=\"684c1cdb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-534a1d98 elementor-widget elementor-widget-text-editor\" data-id=\"534a1d98\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.9.2 - 21-12-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div class=\"page-content\"><ol><li><strong>Bintang\u00a0<\/strong>melambangkan Pancasila dan bahwa anggota Kepolisian Daerah Kalimantan Selatan adalah pegawai dan pembela setia Pancasila.<\/li><li><strong>Berlian\u00a0<\/strong>melambangkan bahwa tugas Polisi adalah tugas mulia yang wajib dijunjung tinggi oleh setiap anggota.<\/li><li><strong>Rumah Banjar\u00a0<\/strong>melambangkan Polisi dalam melaksanakan tugas selalu menghormati adat istiadat serta kebudayaan yang terpelihara dengan baik. Tiang penyangga rumah Banjar melambangkan Polisi sebagai aparat penegak hukum, pengayom dan pelindung. Sedangkan tangga dan pintu terbuka melambangkan bahwa Polisi selalu siap melayani.<\/li><li><strong>Alur Sungai Bergelombang\u00a0<\/strong>melambangkan bahwa Polisi selalu mengikuti dinamika situasi masyarakat dalam mengerjakan tugasnya. Empat alur sungai juga melambangkan Catur Prasetya dan tiga gelombang air melambangkan Tribrata yang merupakan pedoman dan kode etik Polri\u00a0<\/li><\/ol><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21f82f47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21f82f47\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-726d2580\" data-id=\"726d2580\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cd42f37 elementor-widget elementor-widget-heading\" data-id=\"6cd42f37\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-lambang\/\">PROFIL POLDA KALSEL<\/a><\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-262bb55c\" data-id=\"262bb55c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e9b3a7e elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"6e9b3a7e\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.9.2 - 21-12-2022 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)));height:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:inline-flex;background-color:#818a91;align-items:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#818a91}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-1d9d860\" href=\"https:\/\/api.whatsapp.com\/send?phone=6282190241110\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-e339bf4\" href=\"https:\/\/www.youtube.com\/@tribratanewskalsel-Didy-74\/videos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-ef35266\" href=\"https:\/\/www.instagram.com\/spripimpoldakalsel\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-ddb0160\" href=\"https:\/\/twitter.com\/bidhumaskalsel\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>LAMBANG KESATUAN Bintang\u00a0melambangkan Pancasila dan bahwa anggota Kepolisian Daerah Kalimantan Selatan adalah pegawai dan pembela setia Pancasila. Berlian\u00a0melambangkan bahwa tugas Polisi adalah tugas mulia yang wajib dijunjung tinggi oleh setiap anggota. Rumah Banjar\u00a0melambangkan Polisi dalam melaksanakan tugas selalu menghormati adat istiadat serta kebudayaan yang terpelihara dengan baik. Tiang penyangga rumah Banjar melambangkan Polisi sebagai aparat&hellip; <a class=\"more-link\" href=\"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/elementor-lambang\/\">Continue reading <span class=\"screen-reader-text\">POLDA KALSEL #lambang<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-135","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-json\/wp\/v2\/pages\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-json\/wp\/v2\/comments?post=135"}],"version-history":[{"count":67,"href":"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-json\/wp\/v2\/pages\/135\/revisions"}],"predecessor-version":[{"id":908,"href":"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-json\/wp\/v2\/pages\/135\/revisions\/908"}],"wp:attachment":[{"href":"https:\/\/kalsel.polri.go.id\/profilpoldakalsel\/wp-json\/wp\/v2\/media?parent=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}